{"id":1717,"date":"2017-07-12T12:23:01","date_gmt":"2017-07-12T10:23:01","guid":{"rendered":"https:\/\/tapemuzik.de\/privacy-policy\/"},"modified":"2018-05-25T16:36:34","modified_gmt":"2018-05-25T14:36:34","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/tapemuzik.de\/en\/privacy-policy\/","title":{"rendered":"Privacy policy"},"content":{"rendered":"[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;3.0.47&#8243;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;3.0.47&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.0.47&#8243; parallax=&#8221;off&#8221; parallax_method=&#8221;on&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;3.0.65&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;]<h1>Privacy Policy<\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span id=\"result_box\" class=\"\" lang=\"en\"><span title=\"Wir freuen uns \u00fcber Ihr Interesse an unserem Online-Shop.\">We appreciate your interest in our online shop. <\/span><span title=\"Der Schutz Ihrer Privatsph\u00e4re ist f\u00fcr uns sehr wichtig.\">The protection of your privacy is very important to us. <\/span><span title=\"Nachstehend informieren wir Sie ausf\u00fchrlich \u00fcber den Umgang mit Ihren Daten. \">Below we inform you in detail about the handling of your data.<\/span><\/span><\/p>\n<p><span id=\"result_box\" class=\"\" lang=\"en\"><span title=\"Nachstehend informieren wir Sie ausf\u00fchrlich \u00fcber den Umgang mit Ihren Daten. \"><br \/><\/span><span title=\"1. Zugriffsdaten und Hosting \"><strong>1. Access data and hosting<\/strong><br \/><\/span><span title=\"Sie k\u00f6nnen unsere Webseiten besuchen, ohne Angaben zu Ihrer Person zu machen.\">You can visit our websites without giving any personal information. <\/span><span title=\"Bei jedem Aufruf einer Webseite speichert der Webserver lediglich automatisch ein sogenanntes Server-Logfile, das z.B.\">Each time a web page is called, the web server merely automatically stores a so-called server log file, which can be used, for example. <\/span><span title=\"den Namen der angeforderten Datei, Ihre IP-Adresse, Datum und Uhrzeit des Abrufs, \u00fcbertragene Datenmenge und den anfragenden Provider (Zugriffsdaten) enth\u00e4lt und den Abruf dokumentiert. \">contains the name of the requested file, your IP address, the date and time of the retrieval, the amount of data transferred and the requesting provider (access data), and documents the retrieval.<br \/><\/span><span title=\"Diese Zugriffsdaten werden ausschlie\u00dflich zum Zwecke der Sicherstellung eines st\u00f6rungsfreien Betriebs der Seite sowie der Verbesserung unseres Angebots ausgewertet.\">These access data are evaluated exclusively for the purpose of ensuring a trouble-free operation of the site as well as the improvement of our offer. <\/span><span title=\"Dies dient gem\u00e4\u00df Art. 6 Abs. 1 S. 1 lit.\">In accordance with Art. 6 para. 1 sentence 1 lit. <\/span><span title=\"f DSGVO der Wahrung unserer im Rahmen einer Interessensabw\u00e4gung \u00fcberwiegenden berechtigten Interessen an einer korrekten Darstellung unseres Angebots.\">F DSGVO the preservation of our legitimate interests, which predominate in the context of a weighing up of interests, in a correct presentation of our offer. <\/span><span title=\"Alle Zugriffsdaten werden sp\u00e4testens sieben Tage nach Ende Ihres Seitenbesuchs gel\u00f6scht. \">All access data will be deleted no later than seven days after the end of your page visit.<br \/><\/span><span title=\"Hostingdienstleistungen durch einen Drittanbieter \">Hosting services by a third party<br \/><\/span><span title=\"Im Rahmen einer Verarbeitung in unserem Auftrag erbringt ein Drittanbieter f\u00fcr uns die Dienste zum Hosting und zur Darstellung der Webseite.\">Within the framework of a processing on our behalf, a third party provider provides the services for hosting and displaying the website. <\/span><span title=\"Dies dient der Wahrung unserer im Rahmen einer Interessensabw\u00e4gung \u00fcberwiegenden berechtigten Interessen an einer korrekten Darstellung unseres Angebots.\">This serves to safeguard our legitimate interests, which are predominantly justified in the interests of weighing up our interests, in order to correctly present our offer. <\/span><span title=\"Alle Daten, die im Rahmen der Nutzung dieser Webseite oder in daf\u00fcr vorgesehenen Formularen im Onlineshop wie folgend beschrieben erhoben werden, werden auf seinen Servern verarbeitet.\">All data collected as part of the use of this website or in designated forms in the online shop as described below will be processed on its servers. <\/span><span title=\"Eine Verarbeitung auf anderen Servern findet nur in dem hier erl\u00e4uterten Rahmen statt. \">Processing on other servers takes place only in the frame explained here.<br \/><\/span><span title=\"Dieser Dienstleister sitzt innerhalb eines Landes der Europ\u00e4ischen Union oder des Europ\u00e4ischen Wirtschaftsraums. \">This service provider is located within a country of the European Union or the European Economic Area.<\/span><\/span><\/p>\n<p><span id=\"result_box\" class=\"\" lang=\"en\"><span title=\"Dieser Dienstleister sitzt innerhalb eines Landes der Europ\u00e4ischen Union oder des Europ\u00e4ischen Wirtschaftsraums. \"><br \/><\/span><span title=\"2. Datenerhebung und -verwendung zur Vertragsabwicklung und bei Er\u00f6ffnung eines Kundenkontos \"><strong>2. Data collection and use for contract processing and opening a customer account<\/strong><br \/><\/span><span title=\"Wir erheben personenbezogene Daten, wenn Sie uns diese im Rahmen Ihrer Bestellung, bei einer Kontaktaufnahme mit uns (z.B. per Kontaktformular oder E-Mail) oder bei Er\u00f6ffnung eines Kundenkontos freiwillig mitteilen.\">We collect personal information if you voluntarily provide it to us as part of your order, when contacting us (for example, by contact form or e-mail) or when opening a customer account. <\/span><span title=\"Pflichtfelder werden als solche gekennzeichnet, da wir in diesen F\u00e4llen die Daten zwingend zur Vertragsabwicklung, bzw. zur Bearbeitung Ihrer Kontaktaufnahme oder Er\u00f6ffnung des Kundenkontos ben\u00f6tigen und Sie ohne deren Angabe die Bestellung und\/ oder die Kontoer\u00f6ffnung nicht abschlie\u00dfen, bzw. die Kontaktaufnahme nicht versenden k\u00f6nnen\">Obligatory fields are marked as such, since in these cases we need the data for contract execution, or to process your contact or opening the customer account and you can not complete the order and \/ or opening the account without their information, or can not send the contact <\/span><span title=\".\">, <\/span><span title=\"Welche Daten erhoben werden, ist aus den jeweiligen Eingabeformularen ersichtlich.\">Which data are collected, can be seen from the respective input forms. <\/span><span title=\"Wir verwenden die von ihnen mitgeteilten Daten gem\u00e4\u00df Art. 6 Abs. 1 S. 1 lit.\">We use the data communicated by you in accordance with Art. 6 para. 1 sentence 1 lit. <\/span><span title=\"b DSGVO zur Vertragsabwicklung und Bearbeitung Ihrer Anfragen.\">b DSGVO for contract handling and processing of your inquiries. <\/span><span title=\"Nach vollst\u00e4ndiger Abwicklung des Vertrages oder L\u00f6schung Ihres Kundenkontos werden Ihre Daten f\u00fcr die weitere Verarbeitung eingeschr\u00e4nkt und nach Ablauf der steuer- und handelsrechtlichen Aufbewahrungsfristen gel\u00f6scht, sofern Sie nicht ausdr\u00fccklich in eine weitere Nutzung Ihrer Daten eingewilligt haben oder wir uns eine dar\u00fcber hinausgehende Datenverwendung vorbehalten, die\">After completion of the contract or deletion of your customer account, your data will be restricted for further processing and deleted after expiry of the tax and commercial retention periods, unless you have expressly consented to a further use of your data or we reserve the right to further data use, the <\/span><span title=\"gesetzlich erlaubt ist und \u00fcber die wir Sie in dieser Erkl\u00e4rung informieren.\">is legally permitted and about which we inform you in this statement. <\/span><span title=\"Die L\u00f6schung Ihres Kundenkontos ist jederzeit m\u00f6glich und kann entweder durch eine Nachricht an die unten beschriebene Kontaktm\u00f6glichkeit oder \u00fcber eine daf\u00fcr vorgesehene Funktion im Kundenkonto erfolgen. \">The deletion of your customer account is possible at any time and can be done either by a message to the contact option described below or via a designated function in the customer account.<\/span><\/span><\/p>\n<p><span id=\"result_box\" class=\"\" lang=\"en\"><strong><span title=\"Die L\u00f6schung Ihres Kundenkontos ist jederzeit m\u00f6glich und kann entweder durch eine Nachricht an die unten beschriebene Kontaktm\u00f6glichkeit oder \u00fcber eine daf\u00fcr vorgesehene Funktion im Kundenkonto erfolgen. \"><br \/><\/span><\/strong><span title=\"3. Datenweitergabe \"><strong>3. Data transfer<\/strong><br \/><\/span><span title=\"Zur Vertragserf\u00fcllung gem\u00e4\u00df Art. 6 Abs. 1 S. 1 lit.\">For fulfillment of the contract pursuant to Art. 6 para. 1 sentence 1 lit. <\/span><span title=\"b DSGVO geben wir Ihre Daten an das mit der Lieferung beauftragte Versandunternehmen weiter, soweit dies zur Lieferung bestellter Waren erforderlich ist.\">b DSGVO we pass on your data to the shipping company responsible for the delivery, as far as this is necessary for the delivery of ordered goods. <\/span><span title=\"Je nach dem, welchen Zahlungsdienstleister Sie im Bestellprozess ausw\u00e4hlen, geben wir zur Abwicklung von Zahlungen die hierf\u00fcr erhobenen Zahlungsdaten an das mit der Zahlung beauftragte Kreditinstitut und ggf. von uns beauftragte Zahlungsdienstleister weiter bzw. an den ausgew\u00e4hlten Zahlungsdienst.\">Depending on which payment service provider you select in the order process, we will forward payment data collected to the credit institution commissioned with the payment and any payment service providers commissioned by us to process the payments or to the selected payment service. <\/span><span title=\"Zum Teil erheben die ausgew\u00e4hlten Zahlungsdienstleister diese Daten auch selbst, soweit Sie dort ein Konto anlegen.\">In part, the selected payment service providers also collect this data themselves, provided that you create an account there. <\/span><span title=\"In diesem Fall m\u00fcssen Sie sich im Bestellprozess mit Ihren Zugangsdaten bei dem Zahlungsdienstleister anmelden.\">In this case, you must log in to the payment service provider with your access data during the ordering process. <\/span><span title=\"Es gilt insoweit die Datenschutzerkl\u00e4rung des jeweiligen Zahlungsdienstleisters. \">In this respect, the privacy policy of the respective payment service provider applies.<\/span><\/span><\/p>\n<p><span class=\"\" lang=\"en\"><span title=\"Es gilt insoweit die Datenschutzerkl\u00e4rung des jeweiligen Zahlungsdienstleisters. \"><span id=\"result_box\" class=\"\" lang=\"en\" tabindex=\"-1\"><span title=\"4. E-Mail-Newsletter \"><strong>4. E-mail newsletter<\/strong><br \/><\/span><span title=\"E-Mail-Werbung mit Anmeldung zum Newsletter \">E-mail advertising with registration for the newsletter<br \/><\/span><span title=\"Wenn Sie sich zu unserem Newsletter anmelden, verwenden wir die hierf\u00fcr erforderlichen oder gesondert von Ihnen mitgeteilten Daten, um Ihnen regelm\u00e4\u00dfig unseren E-Mail-Newsletter aufgrund Ihrer Einwilligung gem\u00e4\u00df Art. 6 Abs. 1 S. 1 lit.\">If you subscribe to our newsletter, we will use the data required or separately provided by you to regularly send you our e-mail newsletter based on your consent in accordance with Art. 6 para. 1 sentence 1 lit. <\/span><span title=\"a DSGVO zuzusenden. \">to send a DSGVO.<br \/><\/span><span title=\"Die Abmeldung vom Newsletter ist jederzeit m\u00f6glich und kann entweder durch eine Nachricht an die unten beschriebene Kontaktm\u00f6glichkeit oder \u00fcber einen daf\u00fcr vorgesehenen Link im Newsletter erfolgen.\">The deregistration from the newsletter is possible at any time and can be done either by a message to the contact option described below or via a dedicated link in the newsletter. <\/span><span title=\"Nach Abmeldung l\u00f6schen wir Ihre E-Mail-Adresse, soweit Sie nicht ausdr\u00fccklich in eine weitere Nutzung Ihrer Daten eingewilligt haben oder wir uns eine dar\u00fcber hinausgehende Datenverwendung vorbehalten, die gesetzlich erlaubt ist und \u00fcber die wir Sie in dieser Erkl\u00e4rung informieren. \">After unsubscribing we delete your e-mail address, as far as you have not expressly consented to a further use of your data or we reserve the right to further data use, which is permitted by law and about which we inform you in this statement.<br \/><\/span><span title=\"Der Newsletter wird im Rahmen einer Verarbeitung in unserem Auftrag durch einen Dienstleister versendet, an den wir Ihre E-Mail-Adresse hierzu weitergeben. \">The newsletter is sent as part of a processing on our behalf by a service provider, to which we pass on your e-mail address.<br \/><\/span><span title=\"Dieser Dienstleister sitzt innerhalb eines Landes der Europ\u00e4ischen Union oder des Europ\u00e4ischen Wirtschaftsraums. \">This service provider is located within a country of the European Union or the European Economic Area.<\/span><\/span><\/span><\/span><\/p>\n<p><span class=\"\" lang=\"en\"><span title=\"Es gilt insoweit die Datenschutzerkl\u00e4rung des jeweiligen Zahlungsdienstleisters. \"><span id=\"result_box\" class=\"\" lang=\"en\" tabindex=\"-1\"><span title=\"Dieser Dienstleister sitzt innerhalb eines Landes der Europ\u00e4ischen Union oder des Europ\u00e4ischen Wirtschaftsraums. \"><br \/><\/span><span title=\"5. Cookies und Webanalyse \"><strong>5. Cookies and web analytics<\/strong><\/span><\/span><\/span><\/span><\/p>\n<p><span title=\"Um den Besuch unserer Website attraktiv zu gestalten und die Nutzung bestimmter Funktionen zu erm\u00f6glichen, um passende Produkte anzuzeigen oder zur Marktforschung verwenden wir auf verschiedenen Seiten sogenannte Cookies.\">In order to make the visit to our website attractive and to enable the use of certain functions, to display suitable products or for market research, we use so-called cookies on various pages. <\/span><span title=\"Dies dient der Wahrung unserer im Rahmen einer Interessensabw\u00e4gung \u00fcberwiegenden berechtigten Interessen an einer optimierten Darstellung unseres Angebots gem\u00e4\u00df Art. 6 Abs. 1 S. 1 lit.\">This serves to safeguard our legitimate interests, which predominate in the context of a weighing up of interests, in order to optimize the presentation of our offer in accordance with Art. 6 (1) sentence 1 lit. <\/span><span title=\"f DSGVO.\">f DSGVO. <\/span><span title=\"Cookies sind kleine Textdateien, die automatisch auf Ihrem Endger\u00e4t gespeichert werden.\">Cookies are small text files that are automatically stored on your device. <\/span><span title=\"Einige der von uns verwendeten Cookies werden nach Ende der Browser-Sitzung, also nach Schlie\u00dfen Ihres Browsers, wieder gel\u00f6scht (sog. Sitzungs-Cookies).\">Some of the cookies we use are deleted after the end of the browser session, ie after closing your browser (so-called session cookies). <\/span><span title=\"Andere Cookies verbleiben auf Ihrem Endger\u00e4t und erm\u00f6glichen uns, Ihren Browser beim n\u00e4chsten Besuch wiederzuerkennen (persistente Cookies).\">Other cookies remain on your device and allow us to recognize your browser on your next visit (persistent cookies). <\/span><span title=\"Die Dauer der Speicherung k\u00f6nnen Sie der \u00dcbersicht in den Cookie-Einstellungen Ihres Webbrowsers entnehmen.\">The duration of the storage can be found in the overview in the cookie settings of your web browser. <\/span><span title=\"Sie k\u00f6nnen Ihren Browser so einstellen, dass Sie \u00fcber das Setzen von Cookies informiert werden und einzeln \u00fcber deren Annahme entscheiden oder die Annahme von Cookies f\u00fcr bestimmte F\u00e4lle oder generell ausschlie\u00dfen.\">You can set your browser so that you are informed about the setting of cookies and individually decide on their acceptance or exclude the acceptance of cookies for specific cases or in general. <\/span><span title=\"Jeder Browser unterscheidet sich in der Art, wie er die Cookie-Einstellungen verwaltet.\">Each browser differs in the way it manages the cookie settings. <\/span><span title=\"Diese ist in dem Hilfemen\u00fc jedes Browsers beschrieben, welches Ihnen erl\u00e4utert, wie Sie Ihre Cookie-Einstellungen \u00e4ndern k\u00f6nnen.\">This is described in the Help menu of each browser, which explains how to change your cookie settings. <\/span><span title=\"Diese finden Sie f\u00fcr die jeweiligen Browser unter den folgenden Links: \">These can be found for the respective browser under the following links:<br \/><\/span><span title=\"Internet Explorer\u2122: http:\/\/windows.microsoft.com\/de-DE\/windows-vista\/Block-or-allow-cookies \">Internet Explorer \u2122: http:\/\/windows.microsoft.com\/en-US\/windows-vista\/Block-or-allow-cookies<br \/><\/span><span title=\"Safari\u2122: https:\/\/support.apple.com\/kb\/ph21411?locale=de_DE \">Safari \u2122: https:\/\/support.apple.com\/kb\/ph21411?locale=en_US<br \/><\/span><span title=\"Chrome\u2122: http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=de&amp;hlrm=en&amp;answer=95647 \">Chrome \u2122: http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=en&amp;hlrm=en&amp;answer=95647<br \/><\/span><span title=\"Firefox\u2122 https:\/\/support.mozilla.org\/de\/kb\/cookies-erlauben-und-ablehnen \">Firefox \u2122 https:\/\/support.mozilla.org\/en\/kb\/cookies-allow-and-recognize<br \/><\/span><span title=\"Opera\u2122 : http:\/\/help.opera.com\/Windows\/10.20\/de\/cookies.html \">Opera \u2122: http:\/\/help.opera.com\/Windows\/10.20\/en\/cookies.html<br \/><\/span><span title=\"Bei der Nichtannahme von Cookies kann die Funktionalit\u00e4t unserer Website eingeschr\u00e4nkt sein.\">Failure to accept cookies may limit the functionality of our website.<\/span><\/p>\n<p><span class=\"\" lang=\"en\"><span title=\"Es gilt insoweit die Datenschutzerkl\u00e4rung des jeweiligen Zahlungsdienstleisters. \"><span class=\"\" lang=\"en\" tabindex=\"-1\"><span title=\"Bei der Nichtannahme von Cookies kann die Funktionalit\u00e4t unserer Website eingeschr\u00e4nkt sein.\"><span id=\"result_box\" class=\"\" lang=\"en\" tabindex=\"-1\"><span title=\"Einsatz von Google (Universal) Analytics zur Webanalyse \">Use of Google (Universal) Analytics for web analytics<br \/><\/span><span title=\"Zur Webseitenanalyse setzt diese Website Google (Universal) Analytics ein, einen Webanalysedienst der Google LLC (www.google.de).\">For website analysis, this website uses Google (Universal) Analytics, a web analytics service provided by Google LLC (www.google.com). <\/span><span title=\"Dies dient der Wahrung unserer im Rahmen einer Interessensabw\u00e4gung \u00fcberwiegenden berechtigten Interessen an einer optimierten Darstellung unseres Angebots gem\u00e4\u00df Art. 6 Abs. 1 S. 1 lit.\">This serves to safeguard our legitimate interests, which predominate in the context of a weighing up of interests, in order to optimize the presentation of our offer in accordance with Art. 6 (1) sentence 1 lit. <\/span><span title=\"f DSGVO.\">f DSGVO. <\/span><span title=\"Google (Universal) Analytics verwendet Methoden, die eine Analyse der Benutzung der Website durch Sie erm\u00f6glichen, wie zum Beispiel Cookies.\">Google (Universal) Analytics uses methods that allow you to analyze the use of the website, such as cookies. <\/span><span title=\"Die automatisch erhobenen Informationen \u00fcber Ihre Benutzung dieser Website werden in der Regel an einen Server von Google in den USA \u00fcbertragen und dort gespeichert.\">The automatically collected information about your use of this website is usually transmitted to a Google server in the USA and stored there. <\/span><span title=\"Durch die Aktivierung der IP-Anonymisierung auf dieser Webseite wird dabei die IP-Adresse vor der \u00dcbermittlung innerhalb der Mitgliedstaaten der Europ\u00e4ischen Union oder in anderen Vertragsstaaten des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum gek\u00fcrzt.\">By activating IP anonymisation on this website, the IP address will be shortened prior to transmission within the member states of the European Union or in other contracting states of the Agreement on the European Economic Area. <\/span><span title=\"Nur in Ausnahmef\u00e4llen wird die volle IP-Adresse an einen Server von Google in den USA \u00fcbertragen und dort gek\u00fcrzt.\">Only in exceptional cases will the full IP address be sent to a Google server in the US and shortened there. <\/span><span title=\"Die im Rahmen von Google Analytics von Ihrem Browser \u00fcbermittelte anonymisierte IP-Adresse wird grunds\u00e4tzlich nicht mit anderen Daten von Google zusammengef\u00fchrt.\">The anonymized IP address provided by Google Analytics within the framework of Google Analytics will generally not be merged with other data provided by Google. <\/span><span title=\"Nach Zweckfortfall und Ende des Einsatzes von Google Analytics durch uns werden die in diesem Zusammenhang erhobenen Daten gel\u00f6scht. \">After purpose and end of the use of Google Analytics by us, the data collected in this context will be deleted.<br \/><\/span><span title=\"Die Google LLC hat ihren Hauptsitz in den USA und ist zertifiziert unter dem EU-US-Privacy Shield.\">Google LLC is headquartered in the US and is certified under the EU-US Privacy Shield. <\/span><span title=\"Ein aktuelles Zertifikat kann hier eingesehen werden.\">A current certificate can be viewed here. <\/span><span title=\"Aufgrund dieses Abkommens zwischen den USA und der Europ\u00e4ischen Kommission hat letztere f\u00fcr unter dem Privacy Shield zertifizierte Unternehmen ein angemessenes Datenschutzniveau festgestellt. \">Under the agreement between the US and the European Commission, the latter has established an appropriate level of data protection for companies certified under the Privacy Shield.<br \/><\/span><span title=\"Sie k\u00f6nnen die Erfassung der durch das Cookie erzeugten und auf Ihre Nutzung der Website bezogenen Daten (inkl. Ihrer IP-Adresse) an Google sowie die Verarbeitung dieser Daten durch Google verhindern, indem sie das unter dem folgenden Link verf\u00fcgbare Browser-Plugin herunterladen und installieren\">You can prevent the collection of the data (including your IP address) generated by the cookie and related to your use of the website from Google as well as the processing of this data by Google by downloading and installing the browser plug-in available under the following link <\/span><span title=\": http:\/\/tools.google.com\/dlpage\/gaoptout?hl=de \">: http:\/\/tools.google.com\/dlpage\/gaoptout?hl=en<br \/><\/span><span title=\"Alternativ zum Browser-Plugin k\u00f6nnen Sie diesen Link klicken, um die Erfassung durch Google Analytics auf dieser Website zuk\u00fcnftig zu verhindern.\">As an alternative to the browser plug-in, you can click on this link to prevent the collection by Google Analytics on this website in the future. <\/span><span title=\"Dabei wird ein Opt-Out-Cookie auf Ihrem Endger\u00e4t abgelegt.\">An opt-out cookie is stored on your device. <\/span><span title=\"L\u00f6schen Sie Ihre Cookies, m\u00fcssen Sie den Link erneut klicken. \">If you delete your cookies, you must click the link again.<\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span class=\"\" lang=\"en\"><span title=\"Es gilt insoweit die Datenschutzerkl\u00e4rung des jeweiligen Zahlungsdienstleisters. \"><span class=\"\" lang=\"en\" tabindex=\"-1\"><span title=\"Bei der Nichtannahme von Cookies kann die Funktionalit\u00e4t unserer Website eingeschr\u00e4nkt sein.\"><span id=\"result_box\" class=\"\" lang=\"en\" tabindex=\"-1\"><span title=\"L\u00f6schen Sie Ihre Cookies, m\u00fcssen Sie den Link erneut klicken. \"><br \/><\/span><span title=\"6. Kontaktm\u00f6glichkeiten und Ihre Rechte \"><strong>6. Contact options and your rights<\/strong><br \/><\/span><span title=\"Als Betroffener haben Sie folgende Rechte: \u00a0\u00a0\u00a0\u00a0\">As a victim, you have the following rights:<br \/>\u00a0\u00a0\u00a0 <\/span><span title=\"gem\u00e4\u00df Art. 15 DSGVO das Recht, in dem dort bezeichneten Umfang Auskunft \u00fcber Ihre von uns verarbeiteten personenbezogenen Daten zu verlangen; \u00a0\u00a0\u00a0\u00a0\">according to Art. 15 GDPR, the right to demand information on the personal data processed by us in the scope specified therein;<br \/>\u00a0\u00a0\u00a0\u00a0<\/span><span title=\"gem\u00e4\u00df Art. 16 DSGVO das Recht, unverz\u00fcglich die Berichtigung unrichtiger oder Vervollst\u00e4ndigung Ihrer bei uns gespeicherten personenbezogenen Daten zu verlangen; \u00a0\u00a0\u00a0\u00a0\">in accordance with Art. 16 DSGVO the right to demand without delay the correction of incorrect or complete personal data stored with us;<br \/>\u00a0\u00a0\u00a0\u00a0<\/span><span title=\"gem\u00e4\u00df Art. 17 DSGVO das Recht, die L\u00f6schung Ihrer bei uns gespeicherten personenbezogenen Daten zu verlangen, soweit nicht die weitere Verarbeitung \u00a0\u00a0\u00a0\u00a0\">according to Art. 17 DSGVO the right to demand the deletion of your personal data stored by us, unless further processing<br \/>\u00a0\u00a0\u00a0\u00a0<\/span><span title=\"- zur Aus\u00fcbung des Rechts auf freie Meinungs\u00e4u\u00dferung und Information; \u00a0\u00a0\u00a0\u00a0\">&#8211; to exercise the right to freedom of expression and information;<br \/>\u00a0\u00a0\u00a0\u00a0<\/span><span title=\"- zur Erf\u00fcllung einer rechtlichen Verpflichtung; \u00a0\u00a0\u00a0\u00a0\">&#8211; to fulfill a legal obligation;<br \/>\u00a0\u00a0\u00a0\u00a0<\/span><span title=\"- aus Gr\u00fcnden des \u00f6ffentlichen Interesses oder \u00a0\u00a0\u00a0\u00a0\">&#8211; for reasons of public interest or<br \/>\u00a0\u00a0\u00a0\u00a0<\/span><span title=\"- zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen \u00a0\u00a0\u00a0\u00a0\">&#8211; to assert, exercise or defend legal claims<br \/>\u00a0\u00a0\u00a0\u00a0<\/span><span title=\"erforderlich ist; \u00a0\u00a0\u00a0\u00a0\">is required;<br \/>\u00a0\u00a0\u00a0\u00a0<\/span><span title=\"gem\u00e4\u00df Art. 18 DSGVO das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen, soweit \u00a0\u00a0\u00a0\u00a0\">according to Art. 18 DSGVO the right to demand the restriction of the processing of your personal data, as far as<br \/>\u00a0\u00a0\u00a0\u00a0<\/span><span title=\"- die Richtigkeit der Daten von Ihnen bestritten wird; \u00a0\u00a0\u00a0\u00a0\">&#8211; the accuracy of the data is disputed by you;<br \/>\u00a0\u00a0\u00a0\u00a0<\/span><span title=\"- die Verarbeitung unrechtm\u00e4\u00dfig ist, Sie aber deren L\u00f6schung ablehnen; \u00a0\u00a0\u00a0\u00a0\">&#8211; the processing is unlawful, but you reject its deletion;<br \/>\u00a0\u00a0\u00a0\u00a0<\/span><span title=\"- wir die Daten nicht mehr ben\u00f6tigen, Sie diese jedoch zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen ben\u00f6tigen oder \u00a0\u00a0\u00a0\u00a0\">&#8211; we no longer need the data, but you need it for asserting, exercising or defending legal claims or<br \/>\u00a0\u00a0\u00a0\u00a0<\/span><span title=\"- Sie gem\u00e4\u00df Art. 21 DSGVO Widerspruch gegen die Verarbeitung eingelegt haben; \u00a0\u00a0\u00a0\u00a0\">&#8211; you filed an objection against the processing in accordance with Art. 21 GDPR;<br \/>\u00a0\u00a0\u00a0\u00a0<\/span><span title=\"gem\u00e4\u00df Art. 20 DSGVO das Recht, Ihre personenbezogenen Daten, die Sie uns bereitgestellt haben, in einem strukturierten, g\u00e4ngigen und maschinenlesebaren Format zu erhalten oder die \u00dcbermittlung an einen anderen Verantwortlichen zu verlangen; \u00a0\u00a0\u00a0\u00a0\">according to Art. 20 DSGVO the right to receive your personal data, which you have provided us, in a structured, common and machine-readable format or to request the transfer to another person responsible;<br \/>\u00a0\u00a0\u00a0\u00a0<\/span><span title=\"gem\u00e4\u00df Art. 77 DSGVO das Recht, sich bei einer Aufsichtsbeh\u00f6rde zu beschweren.\">according to Art. 77 DSGVO the right to complain to a supervisory authority. <\/span><span title=\"In der Regel k\u00f6nnen Sie sich hierf\u00fcr an die Aufsichtsbeh\u00f6rde Ihres \u00fcblichen Aufenthaltsortes oder Arbeitsplatzes oder unseres Unternehmenssitzes wenden. \">As a rule, you can contact the supervisory authority of your usual place of residence or work or our company headquarters.<\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span title=\"Bei Fragen zur Erhebung, Verarbeitung oder Nutzung Ihrer personenbezogenen Daten, bei Ausk\u00fcnften, Berichtigung, Sperrung oder L\u00f6schung von Daten sowie Widerruf erteilter Einwilligungen oder Widerspruch gegen eine bestimmte Datenverwendung wenden Sie sich bitte direkt an uns \u00fcber die Kontaktdaten in unserem Impressum.\">For questions about the collection, processing or use of your personal data, information, correction, blocking or deletion of data and revocation of granted consent or objection to a particular use of data, please contact us directly via the contact details in our imprint.<\/span><\/p>\n<p><span title=\"Bei Fragen zur Erhebung, Verarbeitung oder Nutzung Ihrer personenbezogenen Daten, bei Ausk\u00fcnften, Berichtigung, Sperrung oder L\u00f6schung von Daten sowie Widerruf erteilter Einwilligungen oder Widerspruch gegen eine bestimmte Datenverwendung wenden Sie sich bitte direkt an uns \u00fcber die Kontaktdaten in unserem Impressum.\"><span id=\"result_box\" class=\"\" lang=\"en\" tabindex=\"-1\"><span title=\"Widerspruchsrecht\n\"><b class=\"b5\">Right <\/b><b class=\"b4\">of<\/b><b class=\"b3\"> re<\/b><b class=\"b2\">fusal<\/b><\/span><\/span><\/span><\/p>\n<p><span title=\"Bei Fragen zur Erhebung, Verarbeitung oder Nutzung Ihrer personenbezogenen Daten, bei Ausk\u00fcnften, Berichtigung, Sperrung oder L\u00f6schung von Daten sowie Widerruf erteilter Einwilligungen oder Widerspruch gegen eine bestimmte Datenverwendung wenden Sie sich bitte direkt an uns \u00fcber die Kontaktdaten in unserem Impressum.\"><span id=\"result_box\" class=\"\" lang=\"en\" tabindex=\"-1\"><span title=\"Soweit wir zur Wahrung unserer im Rahmen einer Interessensabw\u00e4gung \u00fcberwiegenden berechtigten Interessen personenbezogene Daten wie oben erl\u00e4utert verarbeiten, k\u00f6nnen Sie dieser Verarbeitung mit Wirkung f\u00fcr die Zukunft widersprechen.\">To the extent that we process personal data as explained above in order to safeguard our legitimate interests, which are predominant in the context of a weighing up of interests, you can object to this processing with effect for the future. <\/span><span title=\"Erfolgt die Verarbeitung zu Zwecken des Direktmarketings, k\u00f6nnen Sie dieses Recht jederzeit wie oben beschrieben aus\u00fcben.\">If the processing is for the purpose of direct marketing, you can exercise this right at any time as described above. <\/span><span title=\"Soweit die Verarbeitung zu anderen Zwecken erfolgt, steht Ihnen ein Widerspruchsrecht nur bei Vorliegen von Gr\u00fcnden, die sich aus Ihrer besonderen Situation ergeben, zu.\n\n\">Insofar as the processing takes place for other purposes, you are only entitled to a right of objection if there are reasons that arise from your particular situation.<br \/><br \/><\/span><span title=\"Nach Aus\u00fcbung Ihres Widerspruchsrechts werden wir Ihre personenbezogenen Daten nicht weiter zu diesen Zwecken verarbeiten, es sei denn, wir k\u00f6nnen zwingende schutzw\u00fcrdige Gr\u00fcnde f\u00fcr die Verarbeitung nachweisen, die Ihre Interessen, Rechte und Freiheiten \u00fcberwiegen, oder wenn die Verarbeitung der Geltendmachung, Aus\u00fcbung oder Verteidigung von\">After exercising your right to object, we will not further process your personal data for these purposes, unless we can demonstrate compelling legitimate grounds for processing that outweigh your interests, rights and freedoms, or if the processing of the assertion, exercise or defense of <\/span><span title=\"Rechtsanspr\u00fcchen dient.\n\n\">Legal claims serves.<br \/><br \/><\/span><span title=\"Dies gilt nicht, wenn die Verarbeitung zu Zwecken des Direktmarketings erfolgt.\">This does not apply if the processing is for direct marketing purposes. <\/span><span title=\"Dann werden wir Ihre personenbezogenen Daten nicht weiter zu diesem Zweck verarbeiten.\">Then we will not process your personal data for this purpose. <\/span><span title=\"**************************************************\">************************************************** <\/span><span title=\"******************\n\n\n\">******************<br \/><br \/><\/span><span title=\"Datenschutzerkl\u00e4rung erstellt mit dem Trusted Shops Rechtstexter in Kooperation mit Wilde Beuger Solmecke Rechtsanw\u00e4lte.\">Privacy policy created with the Trusted Shops lawyer in cooperation with Wilde Beuger Solmecke lawyers.<\/span><\/span><\/span><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]","protected":false},"excerpt":{"rendered":"<p>Privacy Policy &nbsp; &nbsp; We appreciate your interest in our online shop. The protection of your privacy is very important to us. Below we inform you in detail about the handling of your data. 1. Access data and hostingYou can visit our websites without giving any personal information. Each time a web page is called, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"Wir unterrichten Sie hierdurch gem\u00e4\u00df Telemediengesetz, dass wir personenbezogene Daten durch elektronische Datenverarbeitung (EDV) in dem zum Zwecke der Begr\u00fcndung, inhaltlichen Ausgestaltung oder \u00c4nderung des Vertrages erforderlichen Umfang erheben, verarbeiten und nutzen. Dar\u00fcber hinaus geben wir Ihre Daten selbstverst\u00e4ndlich nicht an Dritte weiter! Mit Bestellung in unserem Shop bevollm\u00e4chtigt der Auftraggeber die Firma AUDIO SERVICE zur \u00dcbermittlung der Angaben zum herzustellenden Tontr\u00e4ger, sowie die Daten des Auftraggebers an die GEMA bzw. der f\u00fcr das jeweilige Land zust\u00e4ndigen Verwertungssgesellschaft. Bei lizenzierungspflichtigen Titeln werden durch die Verwertungsgesellschaft dem Auftraggeber Lizenzgeb\u00fchren in Rechnung gestellt, weiterhin wird eine Ausliefergenehmigung zur Vorlage beim Kopierwerk zugesendet. Die \u00dcbermittlung der Daten ist notwendig in Verbindung mit den Produkten Musikkassette (MC) und 7\"\/12\"-Vinyl-Pressung. F\u00fcr Information oder Auskunft wenden Sie sich bitte an uns, so wie in der Anbieterkennzeichnung bzw. im Impressum angegebenen.","_et_gb_content_width":"","footnotes":""},"class_list":["post-1717","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T.A.P.E. MUZIK - Shop - Privacy policy<\/title>\n<meta name=\"description\" content=\"Privacy policy for orders at the shop for cassettes, in many colors, printed, with pre-recorded ferro- or chrome-tape and duplication.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tapemuzik.de\/en\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T.A.P.E. MUZIK - Shop - Privacy policy\" \/>\n<meta property=\"og:description\" content=\"Privacy policy for orders at the shop for cassettes, in many colors, printed, with pre-recorded ferro- or chrome-tape and duplication.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tapemuzik.de\/en\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"T.A.P.E. MUZIK\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tapemuzik\/\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-25T14:36:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tapemuzik.de\\\/en\\\/privacy-policy\\\/\",\"url\":\"https:\\\/\\\/tapemuzik.de\\\/en\\\/privacy-policy\\\/\",\"name\":\"T.A.P.E. MUZIK - Shop - Privacy policy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tapemuzik.de\\\/en\\\/#website\"},\"datePublished\":\"2017-07-12T10:23:01+00:00\",\"dateModified\":\"2018-05-25T14:36:34+00:00\",\"description\":\"Privacy policy for orders at the shop for cassettes, in many colors, printed, with pre-recorded ferro- or chrome-tape and duplication.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tapemuzik.de\\\/en\\\/privacy-policy\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tapemuzik.de\\\/en\\\/privacy-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tapemuzik.de\\\/en\\\/privacy-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tapemuzik.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tapemuzik.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/tapemuzik.de\\\/en\\\/\",\"name\":\"T.A.P.E. MUZIK\",\"description\":\"Individuelle Kassetten und Zubeh\u00f6r\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tapemuzik.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T.A.P.E. MUZIK - Shop - Privacy policy","description":"Privacy policy for orders at the shop for cassettes, in many colors, printed, with pre-recorded ferro- or chrome-tape and duplication.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tapemuzik.de\/en\/privacy-policy\/","og_locale":"en_US","og_type":"article","og_title":"T.A.P.E. MUZIK - Shop - Privacy policy","og_description":"Privacy policy for orders at the shop for cassettes, in many colors, printed, with pre-recorded ferro- or chrome-tape and duplication.","og_url":"https:\/\/tapemuzik.de\/en\/privacy-policy\/","og_site_name":"T.A.P.E. MUZIK","article_publisher":"https:\/\/www.facebook.com\/tapemuzik\/","article_modified_time":"2018-05-25T14:36:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tapemuzik.de\/en\/privacy-policy\/","url":"https:\/\/tapemuzik.de\/en\/privacy-policy\/","name":"T.A.P.E. MUZIK - Shop - Privacy policy","isPartOf":{"@id":"https:\/\/tapemuzik.de\/en\/#website"},"datePublished":"2017-07-12T10:23:01+00:00","dateModified":"2018-05-25T14:36:34+00:00","description":"Privacy policy for orders at the shop for cassettes, in many colors, printed, with pre-recorded ferro- or chrome-tape and duplication.","breadcrumb":{"@id":"https:\/\/tapemuzik.de\/en\/privacy-policy\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tapemuzik.de\/en\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tapemuzik.de\/en\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tapemuzik.de\/en\/"},{"@type":"ListItem","position":2,"name":"Privacy policy"}]},{"@type":"WebSite","@id":"https:\/\/tapemuzik.de\/en\/#website","url":"https:\/\/tapemuzik.de\/en\/","name":"T.A.P.E. MUZIK","description":"Individuelle Kassetten und Zubeh\u00f6r","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tapemuzik.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/tapemuzik.de\/en\/wp-json\/wp\/v2\/pages\/1717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tapemuzik.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tapemuzik.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tapemuzik.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tapemuzik.de\/en\/wp-json\/wp\/v2\/comments?post=1717"}],"version-history":[{"count":0,"href":"https:\/\/tapemuzik.de\/en\/wp-json\/wp\/v2\/pages\/1717\/revisions"}],"wp:attachment":[{"href":"https:\/\/tapemuzik.de\/en\/wp-json\/wp\/v2\/media?parent=1717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}